{"id":9967,"date":"2024-11-11T13:05:52","date_gmt":"2024-11-11T12:05:52","guid":{"rendered":"https:\/\/hense-systeme.com\/?p=9967"},"modified":"2024-11-12T09:05:27","modified_gmt":"2024-11-12T08:05:27","slug":"notre-affaire-de-coeur-en-cette-periode-de-noel","status":"publish","type":"post","link":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/","title":{"rendered":"Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl :"},"content":{"rendered":"<p class=\"wp-block-paragraph\">En cette p\u00e9riode de No\u00ebl, nous avons \u00e0 c\u0153ur de soutenir une organisation caritative : la \u00ab Fondation allemande contre le cancer de l&#8217;enfant \u00bb. C&#8217;est pourquoi nous avons d\u00e9cid\u00e9 de transformer la valeur des cadeaux de No\u00ebl offerts \u00e0 nos partenaires commerciaux en un don pr\u00e9cieux qui parviendra l\u00e0 o\u00f9 le soutien est n\u00e9cessaire de toute urgence. Et nous savons que nos partenaires commerciaux nous soutiennent pleinement dans cette d\u00e9cision.<\/p>","protected":false},"excerpt":{"rendered":"<p>En cette p\u00e9riode de No\u00ebl, nous avons \u00e0 c\u0153ur de soutenir une organisation caritative : la \u00ab Fondation allemande contre le cancer de l&#8217;enfant \u00bb. C&#8217;est pourquoi nous avons d\u00e9cid\u00e9 de transformer la valeur des cadeaux de No\u00ebl offerts \u00e0 nos partenaires commerciaux en un don pr\u00e9cieux qui parviendra l\u00e0 o\u00f9 le soutien est n\u00e9cessaire &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl :\" class=\"read-more button\" href=\"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/#more-9967\" aria-label=\"En savoir plus sur Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl :\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":9979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","footnotes":""},"categories":[41],"tags":[],"class_list":["post-9967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl : - Hense Systemtechnik GmbH &amp; Co. KG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl : - Hense Systemtechnik GmbH &amp; Co. KG\" \/>\n<meta property=\"og:description\" content=\"En cette p\u00e9riode de No\u00ebl, nous avons \u00e0 c\u0153ur de soutenir une organisation caritative : la \u00ab Fondation allemande contre le cancer de l&#8217;enfant \u00bb. C&#8217;est pourquoi nous avons d\u00e9cid\u00e9 de transformer la valeur des cadeaux de No\u00ebl offerts \u00e0 nos partenaires commerciaux en un don pr\u00e9cieux qui parviendra l\u00e0 o\u00f9 le soutien est n\u00e9cessaire ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/\" \/>\n<meta property=\"og:site_name\" content=\"Hense Systemtechnik GmbH &amp; Co. KG\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-11T12:05:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T08:05:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hense-systeme.com\/wp-content\/uploads\/hense_kinderkrebsstifung_blog_en.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"830\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pixel-admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"pixel-admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/\"},\"author\":{\"name\":\"pixel-admin\",\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/#\\\/schema\\\/person\\\/961cf878f94bdf158c6bb403ae4c89d3\"},\"headline\":\"Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl :\",\"datePublished\":\"2024-11-11T12:05:52+00:00\",\"dateModified\":\"2024-11-12T08:05:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/\"},\"wordCount\":88,\"publisher\":{\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hense-systeme.com\\\/wp-content\\\/uploads\\\/hense_kinderkrebsstifung_blog_en.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/\",\"url\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/\",\"name\":\"Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl : - Hense Systemtechnik GmbH &amp; Co. KG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hense-systeme.com\\\/wp-content\\\/uploads\\\/hense_kinderkrebsstifung_blog_en.jpg\",\"datePublished\":\"2024-11-11T12:05:52+00:00\",\"dateModified\":\"2024-11-12T08:05:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hense-systeme.com\\\/wp-content\\\/uploads\\\/hense_kinderkrebsstifung_blog_en.jpg\",\"contentUrl\":\"https:\\\/\\\/hense-systeme.com\\\/wp-content\\\/uploads\\\/hense_kinderkrebsstifung_blog_en.jpg\",\"width\":830,\"height\":400,\"caption\":\"Hense Systeme unterst\u00fctzt die Kinderkrebsstiftung mit Spenden statt Geschenken 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/notre-affaire-de-coeur-en-cette-periode-de-noel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl :\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/\",\"name\":\"Hense Systemtechnik GmbH &amp; Co. KG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/#organization\",\"name\":\"Hense Systemtechnik GmbH &amp; Co. KG\",\"url\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hense-systeme.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/hense_logo.svg\",\"contentUrl\":\"https:\\\/\\\/hense-systeme.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/hense_logo.svg\",\"width\":241,\"height\":76,\"caption\":\"Hense Systemtechnik GmbH &amp; Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/#\\\/schema\\\/person\\\/961cf878f94bdf158c6bb403ae4c89d3\",\"name\":\"pixel-admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/385460a143c2f867938e6e487079c0662fbf159bbfe70dbb3412078e8dcca679?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/385460a143c2f867938e6e487079c0662fbf159bbfe70dbb3412078e8dcca679?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/385460a143c2f867938e6e487079c0662fbf159bbfe70dbb3412078e8dcca679?s=96&d=mm&r=g\",\"caption\":\"pixel-admin\"},\"sameAs\":[\"https:\\\/\\\/hense-systeme.com\"],\"url\":\"https:\\\/\\\/hense-systeme.com\\\/fr\\\/author\\\/pixel-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl : - Hense Systemtechnik GmbH &amp; Co. KG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/","og_locale":"fr_FR","og_type":"article","og_title":"Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl : - Hense Systemtechnik GmbH &amp; Co. KG","og_description":"En cette p\u00e9riode de No\u00ebl, nous avons \u00e0 c\u0153ur de soutenir une organisation caritative : la \u00ab Fondation allemande contre le cancer de l&#8217;enfant \u00bb. C&#8217;est pourquoi nous avons d\u00e9cid\u00e9 de transformer la valeur des cadeaux de No\u00ebl offerts \u00e0 nos partenaires commerciaux en un don pr\u00e9cieux qui parviendra l\u00e0 o\u00f9 le soutien est n\u00e9cessaire ... Lire plus","og_url":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/","og_site_name":"Hense Systemtechnik GmbH &amp; Co. KG","article_published_time":"2024-11-11T12:05:52+00:00","article_modified_time":"2024-11-12T08:05:27+00:00","og_image":[{"width":830,"height":400,"url":"https:\/\/hense-systeme.com\/wp-content\/uploads\/hense_kinderkrebsstifung_blog_en.jpg","type":"image\/jpeg"}],"author":"pixel-admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"pixel-admin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/#article","isPartOf":{"@id":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/"},"author":{"name":"pixel-admin","@id":"https:\/\/hense-systeme.com\/fr\/#\/schema\/person\/961cf878f94bdf158c6bb403ae4c89d3"},"headline":"Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl :","datePublished":"2024-11-11T12:05:52+00:00","dateModified":"2024-11-12T08:05:27+00:00","mainEntityOfPage":{"@id":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/"},"wordCount":88,"publisher":{"@id":"https:\/\/hense-systeme.com\/fr\/#organization"},"image":{"@id":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/#primaryimage"},"thumbnailUrl":"https:\/\/hense-systeme.com\/wp-content\/uploads\/hense_kinderkrebsstifung_blog_en.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/","url":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/","name":"Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl : - Hense Systemtechnik GmbH &amp; Co. KG","isPartOf":{"@id":"https:\/\/hense-systeme.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/#primaryimage"},"image":{"@id":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/#primaryimage"},"thumbnailUrl":"https:\/\/hense-systeme.com\/wp-content\/uploads\/hense_kinderkrebsstifung_blog_en.jpg","datePublished":"2024-11-11T12:05:52+00:00","dateModified":"2024-11-12T08:05:27+00:00","breadcrumb":{"@id":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/#primaryimage","url":"https:\/\/hense-systeme.com\/wp-content\/uploads\/hense_kinderkrebsstifung_blog_en.jpg","contentUrl":"https:\/\/hense-systeme.com\/wp-content\/uploads\/hense_kinderkrebsstifung_blog_en.jpg","width":830,"height":400,"caption":"Hense Systeme unterst\u00fctzt die Kinderkrebsstiftung mit Spenden statt Geschenken 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/hense-systeme.com\/fr\/notre-affaire-de-coeur-en-cette-periode-de-noel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hense-systeme.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Notre affaire de c\u0153ur en cette p\u00e9riode de No\u00ebl :"}]},{"@type":"WebSite","@id":"https:\/\/hense-systeme.com\/fr\/#website","url":"https:\/\/hense-systeme.com\/fr\/","name":"Hense Systemtechnik GmbH &amp; Co. KG","description":"","publisher":{"@id":"https:\/\/hense-systeme.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hense-systeme.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hense-systeme.com\/fr\/#organization","name":"Hense Systemtechnik GmbH &amp; Co. KG","url":"https:\/\/hense-systeme.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hense-systeme.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/hense-systeme.com\/wp-content\/uploads\/2024\/02\/hense_logo.svg","contentUrl":"https:\/\/hense-systeme.com\/wp-content\/uploads\/2024\/02\/hense_logo.svg","width":241,"height":76,"caption":"Hense Systemtechnik GmbH &amp; Co. KG"},"image":{"@id":"https:\/\/hense-systeme.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/hense-systeme.com\/fr\/#\/schema\/person\/961cf878f94bdf158c6bb403ae4c89d3","name":"pixel-admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/385460a143c2f867938e6e487079c0662fbf159bbfe70dbb3412078e8dcca679?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/385460a143c2f867938e6e487079c0662fbf159bbfe70dbb3412078e8dcca679?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/385460a143c2f867938e6e487079c0662fbf159bbfe70dbb3412078e8dcca679?s=96&d=mm&r=g","caption":"pixel-admin"},"sameAs":["https:\/\/hense-systeme.com"],"url":"https:\/\/hense-systeme.com\/fr\/author\/pixel-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/hense-systeme.com\/fr\/wp-json\/wp\/v2\/posts\/9967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hense-systeme.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hense-systeme.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hense-systeme.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hense-systeme.com\/fr\/wp-json\/wp\/v2\/comments?post=9967"}],"version-history":[{"count":1,"href":"https:\/\/hense-systeme.com\/fr\/wp-json\/wp\/v2\/posts\/9967\/revisions"}],"predecessor-version":[{"id":9973,"href":"https:\/\/hense-systeme.com\/fr\/wp-json\/wp\/v2\/posts\/9967\/revisions\/9973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hense-systeme.com\/fr\/wp-json\/wp\/v2\/media\/9979"}],"wp:attachment":[{"href":"https:\/\/hense-systeme.com\/fr\/wp-json\/wp\/v2\/media?parent=9967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hense-systeme.com\/fr\/wp-json\/wp\/v2\/categories?post=9967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hense-systeme.com\/fr\/wp-json\/wp\/v2\/tags?post=9967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}